{"id":1597,"count":18,"description":"PLA - Polylactic Acid, biologisch abbaubarer und kompostierbarer, Biokunststoff\r\nPE - Polyethylene, Kunststoff","link":"https:\/\/yourpack.eu\/de\/kategorie\/lebensmittelverpackungen\/lunchbox-nudelbox\/","name":"Lunchbox. Nudelbox","slug":"lunchbox-nudelbox","taxonomy":"product_cat","parent":1185,"meta":[],"menu_order":0,"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Lunchbox. Nudelbox - Infigo shop<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/yourpack.eu\/de\/kategorie\/lebensmittelverpackungen\/lunchbox-nudelbox\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lunchbox. Nudelbox - Infigo shop\" \/>\n<meta property=\"og:description\" content=\"PLA &#8211; Polylactic Acid, biologisch abbaubarer und kompostierbarer, Biokunststoff PE &#8211; Polyethylene, Kunststoff\" \/>\n<meta property=\"og:url\" content=\"https:\/\/yourpack.eu\/de\/kategorie\/lebensmittelverpackungen\/lunchbox-nudelbox\/\" \/>\n<meta property=\"og:site_name\" content=\"Infigo shop\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/yourpack.eu\\\/de\\\/kategorie\\\/lebensmittelverpackungen\\\/lunchbox-nudelbox\\\/\",\"url\":\"https:\\\/\\\/yourpack.eu\\\/de\\\/kategorie\\\/lebensmittelverpackungen\\\/lunchbox-nudelbox\\\/\",\"name\":\"Lunchbox. Nudelbox - Infigo shop\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/yourpack.eu\\\/de\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/yourpack.eu\\\/de\\\/kategorie\\\/lebensmittelverpackungen\\\/lunchbox-nudelbox\\\/#breadcrumb\"},\"inLanguage\":\"de\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/yourpack.eu\\\/de\\\/kategorie\\\/lebensmittelverpackungen\\\/lunchbox-nudelbox\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/yourpack.eu\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lebensmittelverpackungen\",\"item\":\"https:\\\/\\\/yourpack.eu\\\/de\\\/kategorie\\\/lebensmittelverpackungen\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Lunchbox. Nudelbox\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/yourpack.eu\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/yourpack.eu\\\/de\\\/\",\"name\":\"Infigo\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/yourpack.eu\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/yourpack.eu\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/yourpack.eu\\\/de\\\/#organization\",\"name\":\"Infigo\",\"url\":\"https:\\\/\\\/yourpack.eu\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/yourpack.eu\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/yourpack.eu\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/2026-Infigo_yourpack-scaled.webp\",\"contentUrl\":\"https:\\\/\\\/yourpack.eu\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/2026-Infigo_yourpack-scaled.webp\",\"width\":2560,\"height\":851,\"caption\":\"Infigo\"},\"image\":{\"@id\":\"https:\\\/\\\/yourpack.eu\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lunchbox. Nudelbox - Infigo shop","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/yourpack.eu\/de\/kategorie\/lebensmittelverpackungen\/lunchbox-nudelbox\/","og_locale":"de_DE","og_type":"article","og_title":"Lunchbox. Nudelbox - Infigo shop","og_description":"PLA &#8211; Polylactic Acid, biologisch abbaubarer und kompostierbarer, Biokunststoff PE &#8211; Polyethylene, Kunststoff","og_url":"https:\/\/yourpack.eu\/de\/kategorie\/lebensmittelverpackungen\/lunchbox-nudelbox\/","og_site_name":"Infigo shop","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/yourpack.eu\/de\/kategorie\/lebensmittelverpackungen\/lunchbox-nudelbox\/","url":"https:\/\/yourpack.eu\/de\/kategorie\/lebensmittelverpackungen\/lunchbox-nudelbox\/","name":"Lunchbox. Nudelbox - Infigo shop","isPartOf":{"@id":"https:\/\/yourpack.eu\/de\/#website"},"breadcrumb":{"@id":"https:\/\/yourpack.eu\/de\/kategorie\/lebensmittelverpackungen\/lunchbox-nudelbox\/#breadcrumb"},"inLanguage":"de"},{"@type":"BreadcrumbList","@id":"https:\/\/yourpack.eu\/de\/kategorie\/lebensmittelverpackungen\/lunchbox-nudelbox\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/yourpack.eu\/de\/"},{"@type":"ListItem","position":2,"name":"Lebensmittelverpackungen","item":"https:\/\/yourpack.eu\/de\/kategorie\/lebensmittelverpackungen\/"},{"@type":"ListItem","position":3,"name":"Lunchbox. Nudelbox"}]},{"@type":"WebSite","@id":"https:\/\/yourpack.eu\/de\/#website","url":"https:\/\/yourpack.eu\/de\/","name":"Infigo","description":"","publisher":{"@id":"https:\/\/yourpack.eu\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/yourpack.eu\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/yourpack.eu\/de\/#organization","name":"Infigo","url":"https:\/\/yourpack.eu\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/yourpack.eu\/de\/#\/schema\/logo\/image\/","url":"https:\/\/yourpack.eu\/wp-content\/uploads\/2026\/02\/2026-Infigo_yourpack-scaled.webp","contentUrl":"https:\/\/yourpack.eu\/wp-content\/uploads\/2026\/02\/2026-Infigo_yourpack-scaled.webp","width":2560,"height":851,"caption":"Infigo"},"image":{"@id":"https:\/\/yourpack.eu\/de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/yourpack.eu\/de\/wp-json\/wp\/v2\/product_cat\/1597","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/yourpack.eu\/de\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/yourpack.eu\/de\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/yourpack.eu\/de\/wp-json\/wp\/v2\/product_cat\/1185"}],"wp:post_type":[{"href":"https:\/\/yourpack.eu\/de\/wp-json\/wp\/v2\/product?product_cat=1597"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}