{"id":72662,"date":"2026-05-04T21:10:07","date_gmt":"2026-05-04T18:10:07","guid":{"rendered":"https:\/\/yourpack.eu\/toode\/lunchbox-195x14x48-cm-breite-x-lange-x-hohe-1500-ml-pappe-mit-pla-beschichtung-braun-braun-310-g-m%c2%b2-fsc-certified-150-stk-karton\/"},"modified":"2026-05-14T01:20:07","modified_gmt":"2026-05-13T22:20:07","slug":"lunchbox-195x14x48-cm-breite-x-lange-x-hohe-1500-ml-pappe-mit-pla-beschichtung-braun-braun-310-g-m%c2%b2-fsc-certified-150-stk-karton","status":"publish","type":"product","link":"https:\/\/yourpack.eu\/de\/artikel\/lunchbox-195x14x48-cm-breite-x-lange-x-hohe-1500-ml-pappe-mit-pla-beschichtung-braun-braun-310-g-m%c2%b2-fsc-certified-150-stk-karton\/","title":{"rendered":"Lunchbox 19,5x14x4,8 cm (Breite x L\u00e4nge X H\u00f6he) 1500 ml, Pappe mit PLA-Beschichtung braun\/braun 310 g\/m\u00b2 FSC\u00ae certified, 150 Stk\/Karton"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":72739,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[1597],"product_tag":[],"class_list":{"0":"post-72662","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-lunchbox-nudelbox","8":"first","9":"instock","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Lunchbox 19,5x14x4,8 cm (Breite x L\u00e4nge X H\u00f6he) 1500 ml, Pappe mit PLA-Beschichtung braun\/braun 310 g\/m\u00b2 FSC\u00ae certified, 150 Stk\/Karton - Infigo shop<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/yourpack.eu\/de\/artikel\/lunchbox-195x14x48-cm-breite-x-lange-x-hohe-1500-ml-pappe-mit-pla-beschichtung-braun-braun-310-g-m%c2%b2-fsc-certified-150-stk-karton\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lunchbox 19,5x14x4,8 cm (Breite x L\u00e4nge X H\u00f6he) 1500 ml, Pappe mit PLA-Beschichtung braun\/braun 310 g\/m\u00b2 FSC\u00ae certified, 150 Stk\/Karton - Infigo shop\" \/>\n<meta property=\"og:url\" content=\"https:\/\/yourpack.eu\/de\/artikel\/lunchbox-195x14x48-cm-breite-x-lange-x-hohe-1500-ml-pappe-mit-pla-beschichtung-braun-braun-310-g-m%c2%b2-fsc-certified-150-stk-karton\/\" \/>\n<meta property=\"og:site_name\" content=\"Infigo shop\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T22:20:07+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/yourpack.eu\\\/de\\\/artikel\\\/lunchbox-195x14x48-cm-breite-x-lange-x-hohe-1500-ml-pappe-mit-pla-beschichtung-braun-braun-310-g-m%c2%b2-fsc-certified-150-stk-karton\\\/\",\"url\":\"https:\\\/\\\/yourpack.eu\\\/de\\\/artikel\\\/lunchbox-195x14x48-cm-breite-x-lange-x-hohe-1500-ml-pappe-mit-pla-beschichtung-braun-braun-310-g-m%c2%b2-fsc-certified-150-stk-karton\\\/\",\"name\":\"Lunchbox 19,5x14x4,8 cm (Breite x L\u00e4nge X H\u00f6he) 1500 ml, Pappe mit PLA-Beschichtung braun\\\/braun 310 g\\\/m\u00b2 FSC\u00ae certified, 150 Stk\\\/Karton - Infigo shop\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/yourpack.eu\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/yourpack.eu\\\/de\\\/artikel\\\/lunchbox-195x14x48-cm-breite-x-lange-x-hohe-1500-ml-pappe-mit-pla-beschichtung-braun-braun-310-g-m%c2%b2-fsc-certified-150-stk-karton\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/yourpack.eu\\\/de\\\/artikel\\\/lunchbox-195x14x48-cm-breite-x-lange-x-hohe-1500-ml-pappe-mit-pla-beschichtung-braun-braun-310-g-m%c2%b2-fsc-certified-150-stk-karton\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/yourpack.eu\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/noodle-box_876111.jpg\",\"datePublished\":\"2026-05-04T18:10:07+00:00\",\"dateModified\":\"2026-05-13T22:20:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/yourpack.eu\\\/de\\\/artikel\\\/lunchbox-195x14x48-cm-breite-x-lange-x-hohe-1500-ml-pappe-mit-pla-beschichtung-braun-braun-310-g-m%c2%b2-fsc-certified-150-stk-karton\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/yourpack.eu\\\/de\\\/artikel\\\/lunchbox-195x14x48-cm-breite-x-lange-x-hohe-1500-ml-pappe-mit-pla-beschichtung-braun-braun-310-g-m%c2%b2-fsc-certified-150-stk-karton\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/yourpack.eu\\\/de\\\/artikel\\\/lunchbox-195x14x48-cm-breite-x-lange-x-hohe-1500-ml-pappe-mit-pla-beschichtung-braun-braun-310-g-m%c2%b2-fsc-certified-150-stk-karton\\\/#primaryimage\",\"url\":\"https:\\\/\\\/yourpack.eu\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/noodle-box_876111.jpg\",\"contentUrl\":\"https:\\\/\\\/yourpack.eu\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/noodle-box_876111.jpg\",\"width\":2500,\"height\":2500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/yourpack.eu\\\/de\\\/artikel\\\/lunchbox-195x14x48-cm-breite-x-lange-x-hohe-1500-ml-pappe-mit-pla-beschichtung-braun-braun-310-g-m%c2%b2-fsc-certified-150-stk-karton\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/yourpack.eu\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Online-Shop\",\"item\":\"https:\\\/\\\/yourpack.eu\\\/de\\\/products\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Lunchbox 19,5x14x4,8 cm (Breite x L\u00e4nge X H\u00f6he) 1500 ml, Pappe mit PLA-Beschichtung braun\\\/braun 310 g\\\/m\u00b2 FSC\u00ae certified, 150 Stk\\\/Karton\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/yourpack.eu\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/yourpack.eu\\\/de\\\/\",\"name\":\"Infigo\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/yourpack.eu\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/yourpack.eu\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/yourpack.eu\\\/de\\\/#organization\",\"name\":\"Infigo\",\"url\":\"https:\\\/\\\/yourpack.eu\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/yourpack.eu\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/yourpack.eu\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/2026-Infigo_yourpack-scaled.webp\",\"contentUrl\":\"https:\\\/\\\/yourpack.eu\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/2026-Infigo_yourpack-scaled.webp\",\"width\":2560,\"height\":851,\"caption\":\"Infigo\"},\"image\":{\"@id\":\"https:\\\/\\\/yourpack.eu\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lunchbox 19,5x14x4,8 cm (Breite x L\u00e4nge X H\u00f6he) 1500 ml, Pappe mit PLA-Beschichtung braun\/braun 310 g\/m\u00b2 FSC\u00ae certified, 150 Stk\/Karton - Infigo shop","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/yourpack.eu\/de\/artikel\/lunchbox-195x14x48-cm-breite-x-lange-x-hohe-1500-ml-pappe-mit-pla-beschichtung-braun-braun-310-g-m%c2%b2-fsc-certified-150-stk-karton\/","og_locale":"de_DE","og_type":"article","og_title":"Lunchbox 19,5x14x4,8 cm (Breite x L\u00e4nge X H\u00f6he) 1500 ml, Pappe mit PLA-Beschichtung braun\/braun 310 g\/m\u00b2 FSC\u00ae certified, 150 Stk\/Karton - Infigo shop","og_url":"https:\/\/yourpack.eu\/de\/artikel\/lunchbox-195x14x48-cm-breite-x-lange-x-hohe-1500-ml-pappe-mit-pla-beschichtung-braun-braun-310-g-m%c2%b2-fsc-certified-150-stk-karton\/","og_site_name":"Infigo shop","article_modified_time":"2026-05-13T22:20:07+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/yourpack.eu\/de\/artikel\/lunchbox-195x14x48-cm-breite-x-lange-x-hohe-1500-ml-pappe-mit-pla-beschichtung-braun-braun-310-g-m%c2%b2-fsc-certified-150-stk-karton\/","url":"https:\/\/yourpack.eu\/de\/artikel\/lunchbox-195x14x48-cm-breite-x-lange-x-hohe-1500-ml-pappe-mit-pla-beschichtung-braun-braun-310-g-m%c2%b2-fsc-certified-150-stk-karton\/","name":"Lunchbox 19,5x14x4,8 cm (Breite x L\u00e4nge X H\u00f6he) 1500 ml, Pappe mit PLA-Beschichtung braun\/braun 310 g\/m\u00b2 FSC\u00ae certified, 150 Stk\/Karton - Infigo shop","isPartOf":{"@id":"https:\/\/yourpack.eu\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/yourpack.eu\/de\/artikel\/lunchbox-195x14x48-cm-breite-x-lange-x-hohe-1500-ml-pappe-mit-pla-beschichtung-braun-braun-310-g-m%c2%b2-fsc-certified-150-stk-karton\/#primaryimage"},"image":{"@id":"https:\/\/yourpack.eu\/de\/artikel\/lunchbox-195x14x48-cm-breite-x-lange-x-hohe-1500-ml-pappe-mit-pla-beschichtung-braun-braun-310-g-m%c2%b2-fsc-certified-150-stk-karton\/#primaryimage"},"thumbnailUrl":"https:\/\/yourpack.eu\/wp-content\/uploads\/2026\/05\/noodle-box_876111.jpg","datePublished":"2026-05-04T18:10:07+00:00","dateModified":"2026-05-13T22:20:07+00:00","breadcrumb":{"@id":"https:\/\/yourpack.eu\/de\/artikel\/lunchbox-195x14x48-cm-breite-x-lange-x-hohe-1500-ml-pappe-mit-pla-beschichtung-braun-braun-310-g-m%c2%b2-fsc-certified-150-stk-karton\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/yourpack.eu\/de\/artikel\/lunchbox-195x14x48-cm-breite-x-lange-x-hohe-1500-ml-pappe-mit-pla-beschichtung-braun-braun-310-g-m%c2%b2-fsc-certified-150-stk-karton\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/yourpack.eu\/de\/artikel\/lunchbox-195x14x48-cm-breite-x-lange-x-hohe-1500-ml-pappe-mit-pla-beschichtung-braun-braun-310-g-m%c2%b2-fsc-certified-150-stk-karton\/#primaryimage","url":"https:\/\/yourpack.eu\/wp-content\/uploads\/2026\/05\/noodle-box_876111.jpg","contentUrl":"https:\/\/yourpack.eu\/wp-content\/uploads\/2026\/05\/noodle-box_876111.jpg","width":2500,"height":2500},{"@type":"BreadcrumbList","@id":"https:\/\/yourpack.eu\/de\/artikel\/lunchbox-195x14x48-cm-breite-x-lange-x-hohe-1500-ml-pappe-mit-pla-beschichtung-braun-braun-310-g-m%c2%b2-fsc-certified-150-stk-karton\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/yourpack.eu\/de\/"},{"@type":"ListItem","position":2,"name":"Online-Shop","item":"https:\/\/yourpack.eu\/de\/products\/"},{"@type":"ListItem","position":3,"name":"Lunchbox 19,5x14x4,8 cm (Breite x L\u00e4nge X H\u00f6he) 1500 ml, Pappe mit PLA-Beschichtung braun\/braun 310 g\/m\u00b2 FSC\u00ae certified, 150 Stk\/Karton"}]},{"@type":"WebSite","@id":"https:\/\/yourpack.eu\/de\/#website","url":"https:\/\/yourpack.eu\/de\/","name":"Infigo","description":"","publisher":{"@id":"https:\/\/yourpack.eu\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/yourpack.eu\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/yourpack.eu\/de\/#organization","name":"Infigo","url":"https:\/\/yourpack.eu\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/yourpack.eu\/de\/#\/schema\/logo\/image\/","url":"https:\/\/yourpack.eu\/wp-content\/uploads\/2026\/02\/2026-Infigo_yourpack-scaled.webp","contentUrl":"https:\/\/yourpack.eu\/wp-content\/uploads\/2026\/02\/2026-Infigo_yourpack-scaled.webp","width":2560,"height":851,"caption":"Infigo"},"image":{"@id":"https:\/\/yourpack.eu\/de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/yourpack.eu\/de\/wp-json\/wp\/v2\/product\/72662","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/yourpack.eu\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/yourpack.eu\/de\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/yourpack.eu\/de\/wp-json\/wp\/v2\/comments?post=72662"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/yourpack.eu\/de\/wp-json\/wp\/v2\/media\/72739"}],"wp:attachment":[{"href":"https:\/\/yourpack.eu\/de\/wp-json\/wp\/v2\/media?parent=72662"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/yourpack.eu\/de\/wp-json\/wp\/v2\/product_brand?post=72662"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/yourpack.eu\/de\/wp-json\/wp\/v2\/product_cat?post=72662"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/yourpack.eu\/de\/wp-json\/wp\/v2\/product_tag?post=72662"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}